{"id":23749,"date":"2023-12-19T10:08:40","date_gmt":"2023-12-19T15:08:40","guid":{"rendered":"https:\/\/owlshead.com\/nos-ambassadeurs\/"},"modified":"2023-12-19T10:21:49","modified_gmt":"2023-12-19T15:21:49","slug":"our-ambassadors","status":"publish","type":"page","link":"https:\/\/owlshead.com\/en\/our-ambassadors\/","title":{"rendered":"Our ambassadors"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":48,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","footnotes":""},"class_list":["post-23749","page","type-page","status-publish","hentry"],"acf":{"blocs_selection":[{"acf_fc_layout":"section_8","section_8_space":[],"section_8_bg":{"ID":23665,"id":23665,"title":"DSCF6288","filename":"DSCF6288-scaled.jpg","filesize":992976,"url":"https:\/\/owlshead.com\/wp-content\/uploads\/2023\/12\/DSCF6288-scaled.jpg","link":"https:\/\/owlshead.com\/en\/our-ambassadors\/attachment\/dscf6288-2\/","alt":"","author":"48","description":"","caption":"","name":"dscf6288-2","status":"inherit","uploaded_to":23749,"date":"2023-12-14 14:58:03","modified":"2023-12-14 14:58:03","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/owlshead.com\/wp-includes\/images\/media\/default.png","width":2560,"height":1707,"sizes":{"thumbnail":"https:\/\/owlshead.com\/wp-content\/uploads\/2023\/12\/DSCF6288-scaled.jpg","thumbnail-width":128,"thumbnail-height":85,"medium":"https:\/\/owlshead.com\/wp-content\/uploads\/2023\/12\/DSCF6288-512x341.jpg","medium-width":512,"medium-height":341,"medium_large":"https:\/\/owlshead.com\/wp-content\/uploads\/2023\/12\/DSCF6288-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/owlshead.com\/wp-content\/uploads\/2023\/12\/DSCF6288-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/owlshead.com\/wp-content\/uploads\/2023\/12\/DSCF6288-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/owlshead.com\/wp-content\/uploads\/2023\/12\/DSCF6288-2048x1365.jpg","2048x2048-width":2048,"2048x2048-height":1365,"latest":"https:\/\/owlshead.com\/wp-content\/uploads\/2023\/12\/DSCF6288-770x455.jpg","latest-width":770,"latest-height":455,"cta":"https:\/\/owlshead.com\/wp-content\/uploads\/2023\/12\/DSCF6288-680x472.jpg","cta-width":680,"cta-height":472,"slider-promo":"https:\/\/owlshead.com\/wp-content\/uploads\/2023\/12\/DSCF6288-1100x726.jpg","slider-promo-width":1100,"slider-promo-height":726,"image-list":"https:\/\/owlshead.com\/wp-content\/uploads\/2023\/12\/DSCF6288-1115x740.jpg","image-list-width":1115,"image-list-height":740,"banner":"https:\/\/owlshead.com\/wp-content\/uploads\/2023\/12\/DSCF6288-1440x400.jpg","banner-width":1440,"banner-height":400,"square_md":"https:\/\/owlshead.com\/wp-content\/uploads\/2023\/12\/DSCF6288-600x600.jpg","square_md-width":600,"square_md-height":600}},"section_8_title":"","section_8_title_left":false,"section_8_content":"","section_8_link":""},{"acf_fc_layout":"simple_content","simple_content_space":["Haut","Bas"],"simple_content_content":"<h1 style=\"text-align: center;\">Our ambassadors<\/h1>\n"},{"acf_fc_layout":"simple_content","simple_content_space":["Haut","Bas"],"simple_content_content":"<h4 style=\"text-align: center;\">Come meet the people who lighten up the mountain!<\/h4>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">Many faces make up Owl&#8217;s Head&#8217;s community, summer and winter alike. Some of them have become masters in the art of showing the mountain through their eyes. Meet them and be inspired by their content!<\/p>\n"},{"acf_fc_layout":"section_6","espace_6_space":["Haut"],"section_6_section_subtitle":"","section_6_repeater":[{"pattern":false,"image":{"ID":23667,"id":23667,"title":"Ambassadeurs_viviane","filename":"Ambassadeurs_viviane-scaled-e1702570732649.jpg","filesize":657256,"url":"https:\/\/owlshead.com\/wp-content\/uploads\/2023\/12\/Ambassadeurs_viviane-scaled-e1702570732649.jpg","link":"https:\/\/owlshead.com\/en\/our-ambassadors\/attachment\/ambassadeurs_viviane-2\/","alt":"","author":"48","description":"","caption":"","name":"ambassadeurs_viviane-2","status":"inherit","uploaded_to":23749,"date":"2023-12-14 15:15:53","modified":"2023-12-14 15:15:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/owlshead.com\/wp-includes\/images\/media\/default.png","width":1860,"height":2560,"sizes":{"thumbnail":"https:\/\/owlshead.com\/wp-content\/uploads\/2023\/12\/Ambassadeurs_viviane-scaled-e1702570732649.jpg","thumbnail-width":70,"thumbnail-height":96,"medium":"https:\/\/owlshead.com\/wp-content\/uploads\/2023\/12\/Ambassadeurs_viviane-512x705.jpg","medium-width":512,"medium-height":705,"medium_large":"https:\/\/owlshead.com\/wp-content\/uploads\/2023\/12\/Ambassadeurs_viviane-768x1057.jpg","medium_large-width":768,"medium_large-height":1057,"large":"https:\/\/owlshead.com\/wp-content\/uploads\/2023\/12\/Ambassadeurs_viviane-1024x1410.jpg","large-width":1024,"large-height":1410,"1536x1536":"https:\/\/owlshead.com\/wp-content\/uploads\/2023\/12\/Ambassadeurs_viviane-1116x1536.jpg","1536x1536-width":1116,"1536x1536-height":1536,"2048x2048":"https:\/\/owlshead.com\/wp-content\/uploads\/2023\/12\/Ambassadeurs_viviane-1488x2048.jpg","2048x2048-width":1488,"2048x2048-height":2048,"latest":"https:\/\/owlshead.com\/wp-content\/uploads\/2023\/12\/Ambassadeurs_viviane-770x455.jpg","latest-width":770,"latest-height":455,"cta":"https:\/\/owlshead.com\/wp-content\/uploads\/2023\/12\/Ambassadeurs_viviane-680x472.jpg","cta-width":680,"cta-height":472,"slider-promo":"https:\/\/owlshead.com\/wp-content\/uploads\/2023\/12\/Ambassadeurs_viviane-1100x726.jpg","slider-promo-width":1100,"slider-promo-height":726,"image-list":"https:\/\/owlshead.com\/wp-content\/uploads\/2023\/12\/Ambassadeurs_viviane-1115x740.jpg","image-list-width":1115,"image-list-height":740,"banner":"https:\/\/owlshead.com\/wp-content\/uploads\/2023\/12\/Ambassadeurs_viviane-1440x400.jpg","banner-width":1440,"banner-height":400,"square_md":"https:\/\/owlshead.com\/wp-content\/uploads\/2023\/12\/Ambassadeurs_viviane-600x600.jpg","square_md-width":600,"square_md-height":600}},"titre":"","sous-titre":"Vi","contenu":"<p>Meet Vi !<\/p>\n<p>An outdoor enthusiast and photographer extraordinaire, Vi travels the length and breadth of Quebec and the world to inspire you to get outside and play. Follow her mountaineering, hiking and snowshoeing adventures through Owl&#8217;s Head and, who knows, you might discover some hidden gems!<\/p>\n","cta":{"title":"Follow her on Instagram","url":"https:\/\/www.instagram.com\/vigauv\/","target":""},"reverse":true,"link":""}]},{"acf_fc_layout":"section_11","bg_center_big_wrap":true,"bg_center_img":false,"bg_center_underline":"Become an ambassador","bg_center_title":"","bg_center__content":"<p>You are passionate about skiing or snowboarding and want to share your passion with your community? You know how to take advantage of trends on social media? We want to meet you!<\/p>\n<p>&nbsp;<\/p>\n<p>Tell us about yourself and become part of Owl&#8217;s Head&#8217;s great family.<\/p>\n","bg_center_cta":[{"texte":"Ambassadors program","liens":"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLScil7c1nA79dXRcXeZ_D_OwJqP8EWRj-YcoB9fq15_PTBlhWQ\/viewform"}],"bg_center_space":["Haut","Bas"]}],"menu_language_white":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Restaurant Club Haus \u00e0 Owl&#039;s Head<\/title>\n<meta name=\"description\" content=\"Golfeur ou pas, profitez d\u2019un bon repas avec vue sur le golf et les montagnes Vertes. Nous servons les d\u00e9jeuners, d\u00eeners et soupers.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/owlshead.com\/nos-ambassadeurs\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Restaurant Club Haus \u00e0 Owl&#039;s Head\" \/>\n<meta property=\"og:description\" content=\"Golfeur ou pas, profitez d\u2019un bon repas avec vue sur le golf et les montagnes Vertes. Nous servons les d\u00e9jeuners, d\u00eeners et soupers.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/owlshead.com\/nos-ambassadeurs\/\" \/>\n<meta property=\"og:site_name\" content=\"Owl&#039;s Head\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/owlsheadresort\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-19T15:21:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/owlshead.com\\\/nos-ambassadeurs\\\/\",\"url\":\"https:\\\/\\\/owlshead.com\\\/nos-ambassadeurs\\\/\",\"name\":\"Restaurant Club Haus \u00e0 Owl's Head\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/owlshead.com\\\/#website\"},\"datePublished\":\"2023-12-19T15:08:40+00:00\",\"dateModified\":\"2023-12-19T15:21:49+00:00\",\"description\":\"Golfeur ou pas, profitez d\u2019un bon repas avec vue sur le golf et les montagnes Vertes. Nous servons les d\u00e9jeuners, d\u00eeners et soupers.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/owlshead.com\\\/nos-ambassadeurs\\\/#breadcrumb\"},\"inLanguage\":\"en-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/owlshead.com\\\/nos-ambassadeurs\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/owlshead.com\\\/nos-ambassadeurs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/owlshead.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Our ambassadors\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/owlshead.com\\\/#website\",\"url\":\"https:\\\/\\\/owlshead.com\\\/\",\"name\":\"Owl&#039;s Head\",\"description\":\"Hiver comme \u00e9t\u00e9, venez vous amusez \u00e0 la montagne\",\"publisher\":{\"@id\":\"https:\\\/\\\/owlshead.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/owlshead.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/owlshead.com\\\/#organization\",\"name\":\"Owl's Head\",\"url\":\"https:\\\/\\\/owlshead.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\\\/\\\/owlshead.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/owlshead.com\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/owls-head_favicon-1.png\",\"contentUrl\":\"https:\\\/\\\/owlshead.com\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/owls-head_favicon-1.png\",\"width\":1243,\"height\":1243,\"caption\":\"Owl's Head\"},\"image\":{\"@id\":\"https:\\\/\\\/owlshead.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/owlsheadresort\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/destination-owl-s-head\\\/\",\"https:\\\/\\\/www.instagram.com\\\/montowlshead\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Restaurant Club Haus \u00e0 Owl's Head","description":"Golfeur ou pas, profitez d\u2019un bon repas avec vue sur le golf et les montagnes Vertes. Nous servons les d\u00e9jeuners, d\u00eeners et soupers.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/owlshead.com\/nos-ambassadeurs\/","og_locale":"en_US","og_type":"article","og_title":"Restaurant Club Haus \u00e0 Owl's Head","og_description":"Golfeur ou pas, profitez d\u2019un bon repas avec vue sur le golf et les montagnes Vertes. Nous servons les d\u00e9jeuners, d\u00eeners et soupers.","og_url":"https:\/\/owlshead.com\/nos-ambassadeurs\/","og_site_name":"Owl&#039;s Head","article_publisher":"https:\/\/www.facebook.com\/owlsheadresort\/","article_modified_time":"2023-12-19T15:21:49+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/owlshead.com\/nos-ambassadeurs\/","url":"https:\/\/owlshead.com\/nos-ambassadeurs\/","name":"Restaurant Club Haus \u00e0 Owl's Head","isPartOf":{"@id":"https:\/\/owlshead.com\/#website"},"datePublished":"2023-12-19T15:08:40+00:00","dateModified":"2023-12-19T15:21:49+00:00","description":"Golfeur ou pas, profitez d\u2019un bon repas avec vue sur le golf et les montagnes Vertes. Nous servons les d\u00e9jeuners, d\u00eeners et soupers.","breadcrumb":{"@id":"https:\/\/owlshead.com\/nos-ambassadeurs\/#breadcrumb"},"inLanguage":"en-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/owlshead.com\/nos-ambassadeurs\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/owlshead.com\/nos-ambassadeurs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/owlshead.com\/en\/"},{"@type":"ListItem","position":2,"name":"Our ambassadors"}]},{"@type":"WebSite","@id":"https:\/\/owlshead.com\/#website","url":"https:\/\/owlshead.com\/","name":"Owl&#039;s Head","description":"Hiver comme \u00e9t\u00e9, venez vous amusez \u00e0 la montagne","publisher":{"@id":"https:\/\/owlshead.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/owlshead.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-CA"},{"@type":"Organization","@id":"https:\/\/owlshead.com\/#organization","name":"Owl's Head","url":"https:\/\/owlshead.com\/","logo":{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/owlshead.com\/#\/schema\/logo\/image\/","url":"https:\/\/owlshead.com\/wp-content\/uploads\/2018\/10\/owls-head_favicon-1.png","contentUrl":"https:\/\/owlshead.com\/wp-content\/uploads\/2018\/10\/owls-head_favicon-1.png","width":1243,"height":1243,"caption":"Owl's Head"},"image":{"@id":"https:\/\/owlshead.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/owlsheadresort\/","https:\/\/www.linkedin.com\/company\/destination-owl-s-head\/","https:\/\/www.instagram.com\/montowlshead\/"]}]}},"taxonomy_info":[],"featured_image_src_large":false,"author_info":{"display_name":"Solveig Barbeau-Thelle","author_link":"https:\/\/owlshead.com\/en\/author\/solveig-barbeau-thelle\/"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/owlshead.com\/en\/wp-json\/wp\/v2\/pages\/23749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/owlshead.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/owlshead.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/owlshead.com\/en\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/owlshead.com\/en\/wp-json\/wp\/v2\/comments?post=23749"}],"version-history":[{"count":0,"href":"https:\/\/owlshead.com\/en\/wp-json\/wp\/v2\/pages\/23749\/revisions"}],"wp:attachment":[{"href":"https:\/\/owlshead.com\/en\/wp-json\/wp\/v2\/media?parent=23749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}